{"id":995,"date":"2018-12-19T11:05:35","date_gmt":"2018-12-19T11:05:35","guid":{"rendered":"http:\/\/www.apampesp.org\/aps\/?p=995"},"modified":"2018-12-19T11:05:41","modified_gmt":"2018-12-19T11:05:41","slug":"professora-homenageada","status":"publish","type":"post","link":"https:\/\/www.apampesp.org\/aps\/2018\/12\/19\/professora-homenageada\/","title":{"rendered":"Professora homenageada"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img fetchpriority=\"high\" decoding=\"async\" width=\"711\" height=\"1024\" src=\"http:\/\/www.apampesp.org\/aps\/wp-content\/uploads\/2018\/12\/IMG-20181001-WA0016-711x1024.jpg\" alt=\"\" class=\"wp-image-996\" srcset=\"https:\/\/www.apampesp.org\/aps\/wp-content\/uploads\/2018\/12\/IMG-20181001-WA0016-711x1024.jpg 711w, https:\/\/www.apampesp.org\/aps\/wp-content\/uploads\/2018\/12\/IMG-20181001-WA0016-208x300.jpg 208w, https:\/\/www.apampesp.org\/aps\/wp-content\/uploads\/2018\/12\/IMG-20181001-WA0016-187x270.jpg 187w, https:\/\/www.apampesp.org\/aps\/wp-content\/uploads\/2018\/12\/IMG-20181001-WA0016.jpg 720w\" sizes=\"(max-width: 711px) 100vw, 711px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Membro do Conselho Deliberativo e artista pl\u00e1stica, a professora Dagmar Souza foi uma das homenageadas na Solenidade do M\u00e9rito Acad\u00eamico de 2018, realizada na Assembleia Legislativa do Estado de S\u00e3o Paulo, no dia 26 de setembro. Na cerim\u00f4nia, foram concedidos t\u00edtulos honor\u00e1rios a profissionais que se destacaram no \u00e2mbito art\u00edstico no Estado de S\u00e3o Paulo. Quem conhece o trabalho da professora sabe que o t\u00edtulo \u00e9 mais do que merecido!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Membro do Conselho Deliberativo e artista pl&aacute;stica, a professora Dagmar Souza foi uma das homenageadas na Solenidade do M&eacute;rito Acad&ecirc;mico de 2018, realizada na Assembleia Legislativa do Estado de S&atilde;o Paulo, no dia 26 de setembro. Na cerim&ocirc;nia, foram concedidos t&iacute;tulos honor&aacute;rios a profissionais que se destacaram no &acirc;mbito art&iacute;stico no Estado de S&atilde;o Paulo. Quem conhece o trabalho da professora sabe que o t&iacute;tulo &eacute; mais do que merecido!<\/p>\n","protected":false},"author":2,"featured_media":997,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[5],"tags":[],"class_list":["post-995","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacao"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.apampesp.org\/aps\/wp-content\/uploads\/2018\/12\/IMG-20181001-WA0014.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9WoMM-g3","_links":{"self":[{"href":"https:\/\/www.apampesp.org\/aps\/wp-json\/wp\/v2\/posts\/995","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.apampesp.org\/aps\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.apampesp.org\/aps\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.apampesp.org\/aps\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.apampesp.org\/aps\/wp-json\/wp\/v2\/comments?post=995"}],"version-history":[{"count":1,"href":"https:\/\/www.apampesp.org\/aps\/wp-json\/wp\/v2\/posts\/995\/revisions"}],"predecessor-version":[{"id":998,"href":"https:\/\/www.apampesp.org\/aps\/wp-json\/wp\/v2\/posts\/995\/revisions\/998"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.apampesp.org\/aps\/wp-json\/wp\/v2\/media\/997"}],"wp:attachment":[{"href":"https:\/\/www.apampesp.org\/aps\/wp-json\/wp\/v2\/media?parent=995"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.apampesp.org\/aps\/wp-json\/wp\/v2\/categories?post=995"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.apampesp.org\/aps\/wp-json\/wp\/v2\/tags?post=995"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}