{"id":724,"date":"2018-09-13T14:57:15","date_gmt":"2018-09-13T14:57:15","guid":{"rendered":"http:\/\/www.apampesp.org\/aps\/?p=724"},"modified":"2018-09-13T14:57:15","modified_gmt":"2018-09-13T14:57:15","slug":"mosap-lanca-alerta-de-nova-fraude-contra-servidores-publicos","status":"publish","type":"post","link":"https:\/\/www.apampesp.org\/aps\/2018\/09\/13\/mosap-lanca-alerta-de-nova-fraude-contra-servidores-publicos\/","title":{"rendered":"Mosap lan\u00e7a alerta de nova fraude contra servidores p\u00fablicos"},"content":{"rendered":"<p>O Instituto Mosap &#8211; Movimento Nacional dos Servidores P\u00fablicos Aposentados e Pensionistas &#8211; divulgou um comunicado de alerta para um novo golpe que vem sendo aplicado contra os servidores p\u00fablicos.<\/p>\n<p>A correspond\u00eancia cont\u00e9m o Bras\u00e3o da Rep\u00fablica, para dar um aspecto de documento oficial, e \u00e9 emitida por uma suposta Secretaria de Fundo Previdenci\u00e1rio, sediada em Santos. O conte\u00fado informa que por determina\u00e7\u00e3o da Procuradoria Geral da Fazenda Nacional, o servidor tem direito a receber uma generosa quantia em dinheiro, a t\u00edtulo de &#8220;restitui\u00e7\u00e3o de contribui\u00e7\u00f5es previdenci\u00e1rias descontadas em folha de pagamento, referente aos planos de aposentadoria vigentes \u00e0 \u00e9poca&#8221;.<\/p>\n<p>Por fim, o texto pede que o benefici\u00e1rio se manifeste no per\u00edodo de 10 dias e oferece dois telefones de contato da falsa institui\u00e7\u00e3o. Ao telefonar, o servidor \u00e9 orientado a efetuar um pagamento de aproximadamente R$ 7 mil, a fim de ter liberada a falsa quantia de quase R$ 70 mil.<\/p>\n<p>Divulgamos abaixo um exemplo da correspond\u00eancia que est\u00e1 sendo enviada.<\/p>\n<p>A Apampesp refor\u00e7a o alerta que vem sendo publicado em nosso site, em nosso jornal e em nossas redes sociais. N\u00e3o h\u00e1, em hip\u00f3tese alguma, o ato de PAGAR para RECEBER. Todos os impostos, encargos e honor\u00e1rios j\u00e1 s\u00e3o descontados direto na fonte e o valor que o servidor receber atrav\u00e9s de a\u00e7\u00f5es judiciais ou outros tipos de direitos ser\u00e1 sempre o valor final.<\/p>\n<p>Em caso de d\u00favidas a respeito de correspond\u00eancias ou telefonemas suspeitos, orientamos os nossos associados a entrarem em contato conosco atrav\u00e9s do telefone (11) 3255-6269, ou direto com a sua Regional.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-725\" src=\"http:\/\/www.apampesp.org\/aps\/wp-content\/uploads\/2018\/09\/Documento-MOSAP.jpg\" alt=\"\" width=\"554\" height=\"767\" srcset=\"https:\/\/www.apampesp.org\/aps\/wp-content\/uploads\/2018\/09\/Documento-MOSAP.jpg 554w, https:\/\/www.apampesp.org\/aps\/wp-content\/uploads\/2018\/09\/Documento-MOSAP-217x300.jpg 217w, https:\/\/www.apampesp.org\/aps\/wp-content\/uploads\/2018\/09\/Documento-MOSAP-195x270.jpg 195w\" sizes=\"(max-width: 554px) 100vw, 554px\" \/><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Instituto Mosap &ndash; Movimento Nacional dos Servidores P&uacute;blicos Aposentados e Pensionistas &ndash; divulgou um comunicado de alerta para um novo golpe que vem sendo aplicado contra os servidores p&uacute;blicos. A correspond&ecirc;ncia cont&eacute;m o Bras&atilde;o da Rep&uacute;blica, para dar um aspecto de documento oficial, e &eacute; emitida por uma suposta Secretaria de Fundo Previdenci&aacute;rio, sediada em Santos. O conte&uacute;do informa que por determina&ccedil;&atilde;o da Procuradoria Geral da Fazenda Nacional, o servidor tem direito a receber uma generosa quantia em dinheiro, a t&iacute;tulo de &ldquo;restitui&ccedil;&atilde;o de contribui&ccedil;&otilde;es previdenci&aacute;rias descontadas em folha [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":726,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[5],"tags":[75,76,74,73,68,15],"class_list":["post-724","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacao","tag-alerta","tag-apampesp","tag-fraude","tag-golpe","tag-mosap","tag-reforma-da-previdencia"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.apampesp.org\/aps\/wp-content\/uploads\/2018\/09\/C9C2576B-9D3A-48A5-8ADD-6FB817B71879-1.png","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9WoMM-bG","_links":{"self":[{"href":"https:\/\/www.apampesp.org\/aps\/wp-json\/wp\/v2\/posts\/724","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.apampesp.org\/aps\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.apampesp.org\/aps\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.apampesp.org\/aps\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.apampesp.org\/aps\/wp-json\/wp\/v2\/comments?post=724"}],"version-history":[{"count":1,"href":"https:\/\/www.apampesp.org\/aps\/wp-json\/wp\/v2\/posts\/724\/revisions"}],"predecessor-version":[{"id":727,"href":"https:\/\/www.apampesp.org\/aps\/wp-json\/wp\/v2\/posts\/724\/revisions\/727"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.apampesp.org\/aps\/wp-json\/wp\/v2\/media\/726"}],"wp:attachment":[{"href":"https:\/\/www.apampesp.org\/aps\/wp-json\/wp\/v2\/media?parent=724"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.apampesp.org\/aps\/wp-json\/wp\/v2\/categories?post=724"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.apampesp.org\/aps\/wp-json\/wp\/v2\/tags?post=724"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}