{"id":694,"date":"2018-08-06T16:57:12","date_gmt":"2018-08-06T16:57:12","guid":{"rendered":"http:\/\/www.apampesp.org\/aps\/?p=694"},"modified":"2018-08-06T16:57:12","modified_gmt":"2018-08-06T16:57:12","slug":"comunicado-juridico","status":"publish","type":"post","link":"https:\/\/www.apampesp.org\/aps\/2018\/08\/06\/comunicado-juridico\/","title":{"rendered":"COMUNICADO JUR\u00cdDICO"},"content":{"rendered":"<p>\u00c9 COM GRATA SATISFA\u00c7\u00c3O QUE O DEPARTAMENTO JUR\u00cdDICO DA APAMPESP VEM INFORMAR AOS ASSOCIADOS QUE A GGE \u2013 GRATIFICA\u00c7\u00c3O DE GESTA\u00c7\u00c3O EDUCACIONAL &#8211; institu\u00eddo pela LCE 1.256\/2015, como gratifica\u00e7\u00e3o gen\u00e9rica aos ativos, foi considerado aumento disfar\u00e7ado de vencimentos e, deve ser extens\u00edvel aos aposentados e pensionistas. (Diretor de Escola, Supervisor de Ensino e Dirigente Regional de Ensino).<\/p>\n<p>De acordo com recente Julgamento em Incidente de Resolu\u00e7\u00e3o de Demandas Repetitivas \u2013 IRDR; cujo objetivo \u00e9 a uniformiza\u00e7\u00e3o dos processos da GGE, o \u00d3rg\u00e3o Especial do Tribunal de Justi\u00e7a de S\u00e3o Paulo entendeu por maioria de votos ser cab\u00edvel a extens\u00e3o da GGE aos aposentados e pensionistas.<\/p>\n<p>A Decis\u00e3o aplica-se a todos os processos que ainda n\u00e3o foram julgados e a todos aqueles que vierem a ser propostos.<\/p>\n<p>Cabe ressaltar que n\u00e3o se trata de pagamento administrativo, ou seja, para ter direito ao percebimento do GGE em holerite e valores retroativos, os aposentados e pensionistas (com Paridade) ter\u00e3o que ingressar com a\u00e7\u00e3o Judicial por interm\u00e9dio do nosso Departamento Jur\u00eddico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&Eacute; COM GRATA SATISFA&Ccedil;&Atilde;O QUE O DEPARTAMENTO JUR&Iacute;DICO DA APAMPESP VEM INFORMAR AOS ASSOCIADOS QUE A GGE &ndash; GRATIFICA&Ccedil;&Atilde;O DE GESTA&Ccedil;&Atilde;O EDUCACIONAL &ndash; institu&iacute;do pela LCE 1.256\/2015, como gratifica&ccedil;&atilde;o gen&eacute;rica aos ativos, foi considerado aumento disfar&ccedil;ado de vencimentos e, deve ser extens&iacute;vel aos aposentados e pensionistas. (Diretor de Escola, Supervisor de Ensino e Dirigente Regional de Ensino). De acordo com recente Julgamento em Incidente de Resolu&ccedil;&atilde;o de Demandas Repetitivas &ndash; IRDR; cujo objetivo &eacute; a uniformiza&ccedil;&atilde;o dos processos da GGE, o &Oacute;rg&atilde;o Especial do Tribunal de Justi&ccedil;a de S&atilde;o Paulo [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":695,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[5],"tags":[19,17,18],"class_list":["post-694","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacao","tag-acao-judicial","tag-gge","tag-juridico"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.apampesp.org\/aps\/wp-content\/uploads\/2018\/08\/JURIDICO.jpeg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9WoMM-bc","_links":{"self":[{"href":"https:\/\/www.apampesp.org\/aps\/wp-json\/wp\/v2\/posts\/694","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.apampesp.org\/aps\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.apampesp.org\/aps\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.apampesp.org\/aps\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.apampesp.org\/aps\/wp-json\/wp\/v2\/comments?post=694"}],"version-history":[{"count":1,"href":"https:\/\/www.apampesp.org\/aps\/wp-json\/wp\/v2\/posts\/694\/revisions"}],"predecessor-version":[{"id":696,"href":"https:\/\/www.apampesp.org\/aps\/wp-json\/wp\/v2\/posts\/694\/revisions\/696"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.apampesp.org\/aps\/wp-json\/wp\/v2\/media\/695"}],"wp:attachment":[{"href":"https:\/\/www.apampesp.org\/aps\/wp-json\/wp\/v2\/media?parent=694"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.apampesp.org\/aps\/wp-json\/wp\/v2\/categories?post=694"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.apampesp.org\/aps\/wp-json\/wp\/v2\/tags?post=694"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}