{"id":615,"date":"2018-06-21T15:22:04","date_gmt":"2018-06-21T15:22:04","guid":{"rendered":"http:\/\/www.apampesp.org\/aps\/?p=615"},"modified":"2018-06-21T15:22:04","modified_gmt":"2018-06-21T15:22:04","slug":"ccm-do-iamspe-e-recebida-pelo-governador-marcio-franca-saiba-como-foi-o-encontro","status":"publish","type":"post","link":"https:\/\/www.apampesp.org\/aps\/2018\/06\/21\/ccm-do-iamspe-e-recebida-pelo-governador-marcio-franca-saiba-como-foi-o-encontro\/","title":{"rendered":"CCM do Iamspe \u00e9 recebida pelo Governador M\u00e1rcio Fran\u00e7a. Saiba como foi o encontro"},"content":{"rendered":"<p>Representantes da Comiss\u00e3o Consultiva Mista do Iamspe &#8211; CCM &#8211; presidida pelo professor Guilherme Nascimento e da qual a Apampesp faz parte &#8211; foram recebidos nesta ter\u00e7a-feira, dia 12 de junho, pelo Governador M\u00e1rcio Fran\u00e7a, em seu gabinete no Pal\u00e1cio dos Bandeirantes.<\/p>\n<p>Durante o encontro, os representantes da CCM apresentaram os problemas do Iamspe e apontaram solu\u00e7\u00f5es. Eles tamb\u00e9m pleitearam a contrapartida de 2% por parte do Governo do Estado, al\u00e9m de mais verbas para o Instituto. A CCM tamb\u00e9m reivindicou um Conselho Administrativo, Fiscal e Parit\u00e1rio e uma gest\u00e3o mais democr\u00e1tica para o Iamspe.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-large wp-image-617\" src=\"http:\/\/www.apampesp.org\/aps\/wp-content\/uploads\/2018\/06\/WhatsApp-Image-2018-06-13-at-13.07.27-1-1024x576.jpeg\" alt=\"\" width=\"640\" height=\"360\" srcset=\"https:\/\/www.apampesp.org\/aps\/wp-content\/uploads\/2018\/06\/WhatsApp-Image-2018-06-13-at-13.07.27-1-1024x576.jpeg 1024w, https:\/\/www.apampesp.org\/aps\/wp-content\/uploads\/2018\/06\/WhatsApp-Image-2018-06-13-at-13.07.27-1-300x169.jpeg 300w, https:\/\/www.apampesp.org\/aps\/wp-content\/uploads\/2018\/06\/WhatsApp-Image-2018-06-13-at-13.07.27-1-768x432.jpeg 768w, https:\/\/www.apampesp.org\/aps\/wp-content\/uploads\/2018\/06\/WhatsApp-Image-2018-06-13-at-13.07.27-1-360x203.jpeg 360w, https:\/\/www.apampesp.org\/aps\/wp-content\/uploads\/2018\/06\/WhatsApp-Image-2018-06-13-at-13.07.27-1.jpeg 1280w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/p>\n<p>O Governador se mostrou receptivo \u00e0 ideia de democratiza\u00e7\u00e3o do Instituto e garantiu que n\u00e3o haver\u00e1 falta de dinheiro no final do ano para o Iamspe. As declara\u00e7\u00f5es j\u00e1 indicam um avan\u00e7o em rela\u00e7\u00e3o a postura do ex-Governador Geraldo Alckmin em rela\u00e7\u00e3o \u00e0 autarquia.<\/p>\n<p>No v\u00eddeo, o professor Guilherme Nascimento, presidente da CCM, traz mais informa\u00e7\u00f5es sobre o encontro. Aperte o play e confira!<\/p>\n<div style=\"width: 352px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-615-1\" width=\"352\" height=\"640\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"http:\/\/www.apampesp.org\/aps\/wp-content\/uploads\/2018\/06\/WhatsApp-Video-2018-06-12-at-22.33.17-1-1.mp4?_=1\" \/><a href=\"http:\/\/www.apampesp.org\/aps\/wp-content\/uploads\/2018\/06\/WhatsApp-Video-2018-06-12-at-22.33.17-1-1.mp4\">http:\/\/www.apampesp.org\/aps\/wp-content\/uploads\/2018\/06\/WhatsApp-Video-2018-06-12-at-22.33.17-1-1.mp4<\/a><\/video><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Representantes da Comiss&atilde;o Consultiva Mista do Iamspe &ndash; CCM &ndash; presidida pelo professor Guilherme Nascimento e da qual a Apampesp faz parte &ndash; foram recebidos nesta ter&ccedil;a-feira, dia 12 de junho, pelo Governador M&aacute;rcio Fran&ccedil;a, em seu gabinete no Pal&aacute;cio dos Bandeirantes. Durante o encontro, os representantes da CCM apresentaram os problemas do Iamspe e apontaram solu&ccedil;&otilde;es. Eles tamb&eacute;m pleitearam a contrapartida de 2% por parte do Governo do Estado, al&eacute;m de mais verbas para o Instituto. A CCM tamb&eacute;m reivindicou um Conselho Administrativo, Fiscal e Parit&aacute;rio e uma gest&atilde;o [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":616,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[5],"tags":[40,39,41],"class_list":["post-615","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacao","tag-ccm","tag-guilherme-nascimento","tag-iamspe"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.apampesp.org\/aps\/wp-content\/uploads\/2018\/06\/WhatsApp-Image-2018-06-13-at-13.07.27.jpeg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9WoMM-9V","_links":{"self":[{"href":"https:\/\/www.apampesp.org\/aps\/wp-json\/wp\/v2\/posts\/615","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.apampesp.org\/aps\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.apampesp.org\/aps\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.apampesp.org\/aps\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.apampesp.org\/aps\/wp-json\/wp\/v2\/comments?post=615"}],"version-history":[{"count":1,"href":"https:\/\/www.apampesp.org\/aps\/wp-json\/wp\/v2\/posts\/615\/revisions"}],"predecessor-version":[{"id":619,"href":"https:\/\/www.apampesp.org\/aps\/wp-json\/wp\/v2\/posts\/615\/revisions\/619"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.apampesp.org\/aps\/wp-json\/wp\/v2\/media\/616"}],"wp:attachment":[{"href":"https:\/\/www.apampesp.org\/aps\/wp-json\/wp\/v2\/media?parent=615"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.apampesp.org\/aps\/wp-json\/wp\/v2\/categories?post=615"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.apampesp.org\/aps\/wp-json\/wp\/v2\/tags?post=615"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}