{"id":1329,"date":"2019-04-24T17:38:40","date_gmt":"2019-04-24T17:38:40","guid":{"rendered":"https:\/\/www.apampesp.org\/aps\/?p=1329"},"modified":"2019-05-14T19:17:27","modified_gmt":"2019-05-14T19:17:27","slug":"restam-poucas-vagas-para-passeio-na-vinicola-santa-bruna-saiba-como-garantir-sua-inscricao","status":"publish","type":"post","link":"https:\/\/www.apampesp.org\/aps\/2019\/04\/24\/restam-poucas-vagas-para-passeio-na-vinicola-santa-bruna-saiba-como-garantir-sua-inscricao\/","title":{"rendered":"Restam poucas vagas para passeio na vin\u00edcola Santa Bruna. Saiba como garantir sua inscri\u00e7\u00e3o"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Aniversariante do dia, a professora Martha de Oliveira David acabou de vir \u00e0 Sede Central da Apampesp para garantir a sua participa\u00e7\u00e3o no passeio \u00e0 Vin\u00edcola Santa Bruna, marcado para este s\u00e1bado, dia 27 de abril. Quem ainda n\u00e3o se inscreveu, corra j\u00e1 para garantir a sua vaga!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A Vin\u00edcola Santa Bruna fica em Jarinu, a 72 km de S\u00e3o Paulo, e o passeio custa R$ 170. O valor inclui transporte de ida e volta em um confort\u00e1vel \u00f4nibus de turismo, caf\u00e9 da manh\u00e3, almo\u00e7o com churrasco e m\u00fasica ao vivo, lava-p\u00e9s, degusta\u00e7\u00e3o de vinhos, passeio pelas parreiras de uva, visita monitorada \u00e0 adega, e muito mais.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para se inscrever ou obter mais informa\u00e7\u00f5es, entre em contato agora atrav\u00e9s do fone (11) 3255-6269 (ramal 133) ou pelo Whatsapp (11) 93235-0622.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"558\" src=\"https:\/\/www.apampesp.org\/aps\/wp-content\/uploads\/2019\/04\/vinho-1-1024x558.jpg\" alt=\"\" class=\"wp-image-1330\" srcset=\"https:\/\/www.apampesp.org\/aps\/wp-content\/uploads\/2019\/04\/vinho-1-1024x558.jpg 1024w, https:\/\/www.apampesp.org\/aps\/wp-content\/uploads\/2019\/04\/vinho-1-300x163.jpg 300w, https:\/\/www.apampesp.org\/aps\/wp-content\/uploads\/2019\/04\/vinho-1-768x418.jpg 768w, https:\/\/www.apampesp.org\/aps\/wp-content\/uploads\/2019\/04\/vinho-1-360x196.jpg 360w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Aniversariante do dia, a professora Martha de Oliveira David acabou de vir &agrave; Sede Central da Apampesp para garantir a sua participa&ccedil;&atilde;o no passeio &agrave; Vin&iacute;cola Santa Bruna, marcado para este s&aacute;bado, dia 27 de abril. Quem ainda n&atilde;o se inscreveu, corra j&aacute; para garantir a sua vaga! A Vin&iacute;cola Santa Bruna fica em Jarinu, a 72 km de S&atilde;o Paulo, e o passeio custa R$ 170. O valor inclui transporte de ida e volta em um confort&aacute;vel &ocirc;nibus de turismo, caf&eacute; da manh&atilde;, almo&ccedil;o com churrasco e m&uacute;sica ao [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1331,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[5],"tags":[],"class_list":["post-1329","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacao"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.apampesp.org\/aps\/wp-content\/uploads\/2019\/04\/WhatsApp-Image-2019-04-24-at-14.03.37.jpeg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9WoMM-lr","_links":{"self":[{"href":"https:\/\/www.apampesp.org\/aps\/wp-json\/wp\/v2\/posts\/1329","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.apampesp.org\/aps\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.apampesp.org\/aps\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.apampesp.org\/aps\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.apampesp.org\/aps\/wp-json\/wp\/v2\/comments?post=1329"}],"version-history":[{"count":1,"href":"https:\/\/www.apampesp.org\/aps\/wp-json\/wp\/v2\/posts\/1329\/revisions"}],"predecessor-version":[{"id":1332,"href":"https:\/\/www.apampesp.org\/aps\/wp-json\/wp\/v2\/posts\/1329\/revisions\/1332"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.apampesp.org\/aps\/wp-json\/wp\/v2\/media\/1331"}],"wp:attachment":[{"href":"https:\/\/www.apampesp.org\/aps\/wp-json\/wp\/v2\/media?parent=1329"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.apampesp.org\/aps\/wp-json\/wp\/v2\/categories?post=1329"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.apampesp.org\/aps\/wp-json\/wp\/v2\/tags?post=1329"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}