{"id":1314,"date":"2019-04-16T19:48:45","date_gmt":"2019-04-16T19:48:45","guid":{"rendered":"https:\/\/www.apampesp.org\/aps\/?p=1314"},"modified":"2019-04-16T19:48:56","modified_gmt":"2019-04-16T19:48:56","slug":"apampesp-monta-programacao-especial-para-o-dia-das-maes","status":"publish","type":"post","link":"https:\/\/www.apampesp.org\/aps\/2019\/04\/16\/apampesp-monta-programacao-especial-para-o-dia-das-maes\/","title":{"rendered":"Apampesp monta programa\u00e7\u00e3o especial para o Dia das M\u00e3es"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\nCelebrado no segundo domingo de maio, o Dia das M\u00e3es ganhou uma\nprograma\u00e7\u00e3o especial para as associadas da Apampesp. No pr\u00f3ximo\ndia 10 de maio, das 10h \u00e0s 15h, a Sede Central estar\u00e1 de portas\nabertas para oferecer diversos servi\u00e7os gratuitos ou com descontos\nexcepcionais, incluindo palestras, servi\u00e7os de beleza como limpeza\nde pele, maquiagem, design de sobrancelha, manicure, massagem\nrelaxante e muito mais!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Venha comemorar esta\ndata t\u00e3o importante conosco! Confirme sua presen\u00e7a pelo fone (11)\n3255-6269 (ramal 133), pelo e-mail <a href=\"mailto:amanda@apampesp.org.br\">amanda@apampesp.org.br<\/a>\nou ainda pelo Whatsapp (11) 93235-0622.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Celebrado no segundo domingo de maio, o Dia das M&atilde;es ganhou uma programa&ccedil;&atilde;o especial para as associadas da Apampesp. No pr&oacute;ximo dia 10 de maio, das 10h &agrave;s 15h, a Sede Central estar&aacute; de portas abertas para oferecer diversos servi&ccedil;os gratuitos ou com descontos excepcionais, incluindo palestras, servi&ccedil;os de beleza como limpeza de pele, maquiagem, design de sobrancelha, manicure, massagem relaxante e muito mais! Venha comemorar esta data t&atilde;o importante conosco! Confirme sua presen&ccedil;a pelo fone (11) 3255-6269 (ramal 133), pelo e-mail amanda@apampesp.org.br ou ainda pelo Whatsapp (11) 93235-0622.<\/p>\n","protected":false},"author":2,"featured_media":1315,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[5],"tags":[],"class_list":["post-1314","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacao"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.apampesp.org\/aps\/wp-content\/uploads\/2019\/04\/Informe_maes.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9WoMM-lc","_links":{"self":[{"href":"https:\/\/www.apampesp.org\/aps\/wp-json\/wp\/v2\/posts\/1314","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.apampesp.org\/aps\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.apampesp.org\/aps\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.apampesp.org\/aps\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.apampesp.org\/aps\/wp-json\/wp\/v2\/comments?post=1314"}],"version-history":[{"count":1,"href":"https:\/\/www.apampesp.org\/aps\/wp-json\/wp\/v2\/posts\/1314\/revisions"}],"predecessor-version":[{"id":1316,"href":"https:\/\/www.apampesp.org\/aps\/wp-json\/wp\/v2\/posts\/1314\/revisions\/1316"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.apampesp.org\/aps\/wp-json\/wp\/v2\/media\/1315"}],"wp:attachment":[{"href":"https:\/\/www.apampesp.org\/aps\/wp-json\/wp\/v2\/media?parent=1314"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.apampesp.org\/aps\/wp-json\/wp\/v2\/categories?post=1314"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.apampesp.org\/aps\/wp-json\/wp\/v2\/tags?post=1314"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}